{"id":95,"count":1,"description":"","link":"https:\/\/funwave.in\/blogs\/tag\/top-frozen-french-fries-exporter-india\/","name":"top frozen french fries exporter India","slug":"top-frozen-french-fries-exporter-india","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>top frozen french fries exporter India Archives - funwave<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/funwave.in\/blogs\/tag\/top-frozen-french-fries-exporter-india\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"top frozen french fries exporter India Archives - funwave\" \/>\n<meta property=\"og:url\" content=\"https:\/\/funwave.in\/blogs\/tag\/top-frozen-french-fries-exporter-india\/\" \/>\n<meta property=\"og:site_name\" content=\"funwave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"top frozen french fries exporter India Archives - funwave","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/funwave.in\/blogs\/tag\/top-frozen-french-fries-exporter-india\/","og_locale":"en_US","og_type":"article","og_title":"top frozen french fries exporter India Archives - funwave","og_url":"https:\/\/funwave.in\/blogs\/tag\/top-frozen-french-fries-exporter-india\/","og_site_name":"funwave","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/funwave.in\/blogs\/tag\/top-frozen-french-fries-exporter-india\/","url":"https:\/\/funwave.in\/blogs\/tag\/top-frozen-french-fries-exporter-india\/","name":"top frozen french fries exporter India Archives - funwave","isPartOf":{"@id":"https:\/\/funwave.in\/blogs\/#website"},"breadcrumb":{"@id":"https:\/\/funwave.in\/blogs\/tag\/top-frozen-french-fries-exporter-india\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/funwave.in\/blogs\/tag\/top-frozen-french-fries-exporter-india\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/funwave.in\/blogs\/"},{"@type":"ListItem","position":2,"name":"top frozen french fries exporter India"}]},{"@type":"WebSite","@id":"https:\/\/funwave.in\/blogs\/#website","url":"https:\/\/funwave.in\/blogs\/","name":"funwave","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/funwave.in\/blogs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/funwave.in\/blogs\/wp-json\/wp\/v2\/tags\/95","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/funwave.in\/blogs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/funwave.in\/blogs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/funwave.in\/blogs\/wp-json\/wp\/v2\/posts?tags=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}